{"id":16809,"date":"2023-05-18T10:17:16","date_gmt":"2023-05-18T00:17:16","guid":{"rendered":"https:\/\/www.relationshipsnsw.org.au\/?p=16809"},"modified":"2025-05-14T11:03:54","modified_gmt":"2025-05-14T01:03:54","slug":"stages-of-relationships","status":"publish","type":"post","link":"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/stages-of-relationships\/","title":{"rendered":"Navigare nelle cinque fasi di una relazione per un amore duraturo"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16809\" class=\"elementor elementor-16809\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2166895b e-flex e-con-boxed e-con e-parent\" data-id=\"2166895b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6126b7a6 elementor-widget elementor-widget-text-editor\" data-id=\"6126b7a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Sappiamo tutti che le relazioni sono un duro lavoro, ma se ci fosse una tabella di marcia o una guida per aiutarci a capire meglio e navigare in tutto questo?<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a68586b elementor-widget elementor-widget-text-editor\" data-id=\"3a68586b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quasi tutti noi sappiamo che le relazioni cambiano e si adattano costantemente.\u00a0<span style=\"text-align: var(--text-align); background-color: var(--bs-body-bg); color: var(--bs-body-color); font-family: var(--e-global-typography-primary-font-family); font-size: var(--global-font-size-body-2); font-weight: var(--global-font-weight-body);\">Uno dei modelli pi\u00f9 influenti di sviluppo delle relazioni \u00e8 stato introdotto dallo psicologo tedesco George Levinger. Proposto nel 1976, il suo <\/span><a style=\"text-align: var(--text-align); background-color: var(--bs-body-bg); font-family: var(--e-global-typography-primary-font-family); font-size: var(--global-font-size-body-2); font-weight: var(--global-font-weight-body);\" href=\"https:\/\/spssi.onlinelibrary.wiley.com\/doi\/10.1111\/j.1540-4560.1976.tb02478.x\" target=\"_blank\" rel=\"noopener\">Teoria ABCDE<\/a><span style=\"text-align: var(--text-align); background-color: var(--bs-body-bg); color: var(--bs-body-color); font-family: var(--e-global-typography-primary-font-family); font-size: var(--global-font-size-body-2); font-weight: var(--global-font-weight-body);\"> non sembra molto romantico, ma ogni lettera segna un periodo diverso in ogni relazione:\u00a0<\/span><\/p><ul><li><strong>UN<\/strong>Conoscenza\/Attrazione<\/li><li><strong>B<\/strong>accumulazione<\/li><li><strong>C<\/strong>ontinuazione\/Consolidamento<\/li><li><strong>D<\/strong>deterioramento<\/li><li><strong>E<\/strong>nding<\/li><\/ul><p>Per molte coppie, pu\u00f2 essere rassicurante sapere che la maggior parte delle relazioni attraversa queste varie fasi, ea volte \u00e8 proprio quello che sono: una fase.<\/p><p>Come le cinque fasi di <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/valentines-day-alone\/\" target=\"_blank\" rel=\"noopener\">dolore<\/a>, le cinque fasi delle relazioni possono essere non lineari, ripetute o entrambe.<\/p><div><p><span style=\"text-align: var(--text-align); background-color: var(--bs-body-bg); color: var(--bs-body-color); font-family: var(--e-global-typography-primary-font-family); font-size: var(--global-font-size-body-2); font-weight: var(--global-font-weight-body);\">&quot;Le guide sono sempre utili per attirare la nostra attenzione su alcuni concetti chiave, ma non sono mai esaustive e non sono nemmeno lineari&quot;, spiega la nostra CEO e psicologa clinica, Elisabeth Shaw. &quot;Nelle relazioni, puoi entrare e uscire dalle fasi a seconda degli eventi della vita o delle palle curve della vita.&quot;<\/span><\/p><p>Qui, dettagliamo ogni fase in modo che tu possa capire meglio come si sviluppano le relazioni. Identificando queste fasi di relazione comuni, tu e il tuo partner potete non solo sapere come superare, ma anche prosperare attraverso ogni fase.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60c0156b e-flex e-con-boxed e-con e-parent\" data-id=\"60c0156b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5044f54 elementor-widget elementor-widget-spacer\" data-id=\"5044f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38e762ad elementor-widget elementor-widget-text-editor\" data-id=\"38e762ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>1. Conoscenza\/Attrazione: L&#039;incantevole inizio<\/h2><p>La fase iniziale, spesso nota come <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/starting-new-relationship-advice\/\" target=\"_blank\" rel=\"noopener\">&#039;fase della luna di miele&#039;<\/a> \u00e8 caratterizzato da intensa passione, eccitazione e infatuazione. Le scintille emotive e fisiche sono dilaganti, rendendo questo inizio di solito il momento pi\u00f9 memorabile e amato, poich\u00e9 tutto sembra perfetto. \u00c8 un momento incantevole di scoperta ed esplorazione mentre tu e il tuo partner investite tempo e sforzi per conoscervi.\u00a0<\/p><p>\u00c8 anche importante, tuttavia, tenere i piedi per terra. La combinazione di ossitocina, serotonina e dopamina, rilasciata nel cervello quando sei appena innamorato, aumenta la tua eccitazione e il desiderio reciproco. Di conseguenza, puoi trascurare alcuni tratti o valori che normalmente non vorresti. L&#039;attrazione iniziale pu\u00f2 anche svanire ma il <a href=\"https:\/\/www.scientificamerican.com\/article\/what-physiological-changes-can-explain-honeymoon-phase-relationship\/\" target=\"_blank\" rel=\"noopener\">Scientifico americano<\/a> offre speranza, per\u00f2. Alcune coppie possono sostenere questi sentimenti euforici durante la loro relazione sfidandosi a vicenda con nuove attivit\u00e0 che amano insieme.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22249dde elementor-widget elementor-widget-text-editor\" data-id=\"22249dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>2. Costruzione: il centro intricato<\/h2><p>Questa \u00e8 la fase in cui la realt\u00e0 si assesta e la relazione pu\u00f2 davvero crescere. Potrebbe esserci meno passione che nella fase della &quot;luna di miele&quot;, ma tu e il tuo partner siete ancora legati dall&#039;amore romantico. Non siete pi\u00f9 estranei e avete una buona idea dei reciproci valori e obiettivi. Hai iniziato ad accettare i reciproci difetti e, a tua volta, ti sei sentito pi\u00f9 a tuo agio l&#039;uno con l&#039;altro, costruendo una connessione emotiva ancora pi\u00f9 profonda.<\/p><p>Ironia della sorte, per\u00f2, man mano che la relazione avanza, inevitabilmente sorgono conflitti e sfide. Questa \u00e8 l&#039;intricata fase intermedia, in cui le coppie affrontano vari ostacoli e devono <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/having-difficult-conversations\/\" target=\"_blank\" rel=\"noopener\">navigare disaccordi, differenze<\/a> e le realt\u00e0 della vita quotidiana insieme. Sviluppare una sana <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/how-soft-start-ups-improve-relationship-communication\/\" target=\"_blank\" rel=\"noopener\">modelli di comunicazione<\/a>, <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/become-more-empathetic-relationships\/\" target=\"_blank\" rel=\"noopener\">praticare l&#039;empatia<\/a> e lavorare insieme come una squadra sono fondamentali in questa fase.\u00a0<\/p><p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-562b5d1 elementor-widget elementor-widget-video\" data-id=\"562b5d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/mKZmBTUN_O8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6934c02 elementor-widget elementor-widget-spacer\" data-id=\"6934c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7be97b elementor-widget elementor-widget-text-editor\" data-id=\"e7be97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>3. Continuazione: costruire un futuro insieme<\/h2><p>In questa fase dell&#039;impegno, le coppie cementano la loro dedizione reciproca che pu\u00f2 sbocciare in un futuro condiviso. Vengono fatti piani a lungo termine, vengono stabiliti obiettivi comuni e le connessioni emotive si approfondiscono. Questa fase spesso comporta la costruzione di una vita insieme, come stabilire una carriera, cambiare casa o <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/partner-and-i-disagree-about-having-children\/\">mettere su famiglia<\/a>.<\/p><p>Coltivare la relazione mantenendo un senso di individualit\u00e0 \u00e8 essenziale. Alcune coppie rischiano di diventare co-dipendenti, mentre altre possono risentirsi a causa della mancanza di spazio o dell&#039;eccitazione. Di solito dopo due o tre anni pu\u00f2 comparire un periodo di stagnazione o volatilit\u00e0. <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/fix-common-relationship-issues\/\">Incompatibilit\u00e0 e problemi di fondo<\/a> possono emergere se non vengono affrontati in modo sano, in cui entrambi i partner si sentono compresi. La comunicazione e il compromesso sono importanti qui, poich\u00e9 le coppie entrano in una partnership pi\u00f9 profonda e appagante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e99b396 elementor-widget elementor-widget-text-editor\" data-id=\"e99b396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>4. Deterioramento: creare o distruggere<\/h2><p>A un certo punto, le coppie raggiungono un punto di svolta che pu\u00f2 rafforzare la relazione o portarla alla fine. Questa fase \u00e8 spesso innescata da fattori esterni come cambiamenti significativi nella vita, crisi o <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/help-someone-with-mental-health-issues\/\" target=\"_blank\" rel=\"noopener\">grandi sfide per la salute<\/a>\u00c8 un periodo critico in cui le coppie devono sostenersi a vicenda e <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/\">cercare un aiuto professionale<\/a> se necessario.<\/p><p>Questa svolta pu\u00f2 anche essere il risultato di un&#039;usura generale. Una credenza ampiamente accettata e popolare, sebbene non sia un termine scientifico, \u00e8 l&#039;idea del &quot;prurito di sette anni&quot;, in cui la felicit\u00e0 in una relazione romantica diminuisce dopo circa sette anni.<\/p><p>Mentre <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/find-a-genuine-connection-dating-apps\/\">app di appuntamenti<\/a> hanno reso pi\u00f9 facile trovare un nuovo partner, Elisabeth ci ricorda che &quot;anche se c&#039;\u00e8 il vecchio detto di &#039;molti pi\u00f9 pesci nel mare&#039;, lo scambio di partner richiede un pedaggio&quot;.<\/p><p>Secondo lei, la prova definitiva di una relazione \u00e8 il modo in cui si affrontano le sfide come squadra, in modo che &quot;quando si incontrano difficolt\u00e0, si riesca a superarle bene e ci si senta pi\u00f9 forti e uniti&quot;.<\/p><p>Spesso questo pu\u00f2 essere un processo continuo per le coppie, poich\u00e9 imparano modi produttivi di comunicare, che cementano una solida base per la fase successiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8980de elementor-widget elementor-widget-text-editor\" data-id=\"c8980de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cqte7OoyFrK\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\"background:#FFF;border:0;border-radius:3px;margin: 1px;max-width:540px;min-width:326px;padding:0;width:99.375%;width:-webkit-calc(100% - 2px);width:calc(100% - 2px)\"><div style=\"padding:16px\"> <a href=\"https:\/\/www.instagram.com\/p\/Cqte7OoyFrK\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"background:#FFFFFF;line-height:0;padding:0 0;text-align:center;text-decoration:none;width:100%\" target=\"_blank\" rel=\"noopener\"> <div style=\"flex-direction: row;align-items: center\"> <div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 40px;margin-right: 14px;width: 40px\"><\/div> <div style=\"flex-direction: column;flex-grow: 1;justify-content: center\"> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 100px\"><\/div> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 60px\"><\/div><\/div><\/div><div style=\"padding: 19% 0\"><\/div> <div style=\"height:50px;margin:0 auto 12px;width:50px\"><\/div><div style=\"padding-top: 8px\"> <div style=\"color:#3897f0;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:550;line-height:18px\">Visualizza questo post su Instagram<\/div><\/div><div style=\"padding: 12.5% 0\"><\/div> <div style=\"flex-direction: row;margin-bottom: 14px;align-items: center\"><div> <div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div> <div style=\"background-color: #F4F4F4;height: 12.5px;width: 12.5px;flex-grow: 0;margin-right: 14px;margin-left: 2px\"><\/div> <div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div><\/div><div style=\"margin-left: 8px\"> <div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 20px;width: 20px\"><\/div> <div style=\"width: 0;height: 0;border-top: 2px solid transparent;border-left: 6px solid #f4f4f4;border-bottom: 2px solid transparent\"><\/div><\/div><div style=\"margin-left: auto\"> <div style=\"width: 0px;border-top: 8px solid #F4F4F4;border-right: 8px solid transparent\"><\/div> <div style=\"background-color: #F4F4F4;flex-grow: 0;height: 12px;width: 16px\"><\/div> <div style=\"width: 0;height: 0;border-top: 8px solid #F4F4F4;border-left: 8px solid transparent\"><\/div><\/div><\/div> <div style=\"flex-direction: column;flex-grow: 1;justify-content: center;margin-bottom: 24px\"> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 224px\"><\/div> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 144px\"><\/div><\/div><\/a><p style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;line-height:17px;margin-bottom:0;margin-top:8px;overflow:hidden;padding:8px 0 7px;text-align:center\"><a href=\"https:\/\/www.instagram.com\/p\/Cqte7OoyFrK\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:normal;line-height:17px;text-decoration:none\" target=\"_blank\" rel=\"noopener\">Un post condiviso da Relationships Australia NSW (@relationshipsnsw)<\/a><\/p><\/div><\/blockquote> \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-882912a elementor-widget elementor-widget-text-editor\" data-id=\"882912a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>5. Il finale riuscito o non riuscito<\/h2><p>Nella fase finale, le coppie o superano con successo le sfide e continuano a costruire una relazione appagante, oppure giungono alla consapevolezza che \u00e8 giunto il momento di <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/signs-your-relationship-is-over\/\" target=\"_blank\" rel=\"noopener\">separarsi<\/a>Riflessione e consapevolezza di s\u00e9 sono essenziali per abbracciare la relazione che scegli. Qualunque sia il percorso che prender\u00e0 la tua relazione, \u00e8 importante rimanere onesti e amorevoli con te stesso. Dopotutto, nessuno pu\u00f2 provare quello che provi tu.\u00a0<\/p><p>D&#039;altra parte, l&#039;amore duraturo \u00e8 il culmine di ogni relazione seria. Vi siete veramente accettati l&#039;un l&#039;altro, difetti e tutto il resto, e avete coltivato una relazione contrassegnata da sicurezza, flessibilit\u00e0 e buoni confini. Sebbene sia la fase finale, richiede comunque manutenzione. Puoi ancora tornare alle fasi precedenti, ma questo pu\u00f2 anche includere di nuovo la fase della luna di miele!<\/p><p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ebd715 e-flex e-con-boxed e-con e-parent\" data-id=\"8ebd715\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b477099 elementor-widget elementor-widget-spacer\" data-id=\"b477099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6cf857 elementor-widget elementor-widget-text-editor\" data-id=\"b6cf857\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Se ritieni di aver bisogno di ulteriore supporto per affrontare conversazioni difficili nelle tue relazioni, il supporto \u00e8 disponibile. Offerte di Relationships Australia NSW\u00a0<a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/group-workshops\/couples-communication\/\">programmi di comunicazione di coppia online,<\/a>\u00a0<a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/individual-counselling\/\">consulenza individuale<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/couples-counselling\/\">consulenza di coppia<\/a>. Questi programmi possono aiutarti a sviluppare abilit\u00e0 e strategie per comunicare ed esplorare i problemi con i tuoi cari in modo pi\u00f9 efficace.<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5045474 related-blog-single e-flex e-con-boxed e-con e-parent\" data-id=\"5045474\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1dfa17e1 elementor-widget elementor-widget-heading\" data-id=\"1dfa17e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Servizi e workshop correlati<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d83225c elementor-widget elementor-widget-Elem_Articles_Grid\" data-id=\"3d83225c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Elem_Articles_Grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div id=\"elem-articles-grid-6a988e52cfa5d\" class=\"elem-articles-grid\">\n      \n      <div class=\"elem-articles-grid__posts elem-articles-grid__posts--cpt-service alm-button-style--light\">\n        <div class=\"container\">\n          <div id=\"ajax-load-more\" class=\"ajax-load-more-wrap white\" data-id=\"elem-articles-grid-6a988e52cfa5d\" data-alm-id=\"\" data-canonical-url=\"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/stages-of-relationships\/\" data-slug=\"stages-of-relationships\" data-post-id=\"16809\"  data-localized=\"ajax_load_more_elem_articles_grid_6a988e52cfa5d_vars\" data-alm-object=\"ajax_load_more_elem_articles_grid_6a988e52cfa5d\"><div aria-live=\"polite\" aria-atomic=\"true\" class=\"alm-listing alm-ajax row row-cols-1 row-cols-lg-3\" data-preloaded=\"true\" data-preloaded-amount=\"3\" data-container-type=\"div\" data-loading-style=\"white\" data-archive=\"true\" data-repeater=\"default\" data-post-type=\"post,cpt-workshop,cpt-service,cpt-training\" data-post-in=\"2994,3017,4709\" data-post-not-in=\"24218,23787\" data-vars=\"layout:default\" data-order=\"DESC\" data-orderby=\"date\" data-offset=\"0\" data-posts-per-page=\"6\" data-scroll=\"false\" data-pause=\"true\" data-button-label=\"Load More\" data-prev-button-label=\"Load Previous\" data-images-loaded=\"true\">        <div class=\"col mb-3 mb-lg-4 mb-xxl-5\" data-index=\"1\">\n            <div class=\"comp-blog-card comp-blog-card--default wow fadeIn\" data-wow-delay=\"0s\">\n    <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/couples-counselling\/\" class=\"comp-blog-card__img\">\n      <img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/www.relationshipsnsw.org.au\/wp-content\/uploads\/2022\/10\/RANSW_COUPLES_004_1200px-1-768x515.jpg\" alt=\"Couples Counselling\">\n    <\/a>\n\n    <div class=\"comp-blog-card__content balance-elements\">\n              <p class=\"tag-line\">Consulenza<span class=\"d-inline-block mx-2\">.<\/span>Coppie<span class=\"d-inline-block mx-2\">.<\/span>Lavoro + denaro<span class=\"d-inline-block mx-2\">.<\/span>Multiculturale<\/p>\n      \n      <h4><a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/couples-counselling\/\">Consulenza di coppia<\/a><\/h4>\n\n              <div class=\"d-none d-lg-block\">\n          <p>Le relazioni possono essere difficili e, a volte, tutti abbiamo bisogno di supporto e guida extra per aiutarci ad andare avanti. La consulenza di coppia presso RANSW offre un ambiente favorevole in cui puoi discutere preoccupazioni, superare le tensioni e rafforzare la tua partnership.<\/p>\n        <\/div>\n          <\/div>\n\n    <div class=\"comp-blog-card__link\">\n        <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/couples-counselling\/\"     class=\"comp-button comp-button--default\"\n     tabindex=\"0\" role=\"button\"       >\n    Esplorare  <\/a>\n    <\/div>\n  <\/div>\n        <\/div>\n                <div class=\"col mb-3 mb-lg-4 mb-xxl-5\" data-index=\"2\">\n            <div class=\"comp-blog-card comp-blog-card--default wow fadeIn\" data-wow-delay=\"0.2s\">\n    <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/prepare-enrich-pre-marriage-counselling\/\" class=\"comp-blog-card__img\">\n      <img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/www.relationshipsnsw.org.au\/wp-content\/uploads\/2022\/10\/RANSW_COUPLES_003_1200px-768x515.jpg\" alt=\"Prepare and Enrich\">\n    <\/a>\n\n    <div class=\"comp-blog-card__content balance-elements\">\n              <p class=\"tag-line\">Consulenza<span class=\"d-inline-block mx-2\">.<\/span>Coppie<span class=\"d-inline-block mx-2\">.<\/span>Transizione di vita<\/p>\n      \n      <h4><a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/prepare-enrich-pre-marriage-counselling\/\">Preparare e arricchire<\/a><\/h4>\n\n              <div class=\"d-none d-lg-block\">\n          <p>\u00c8 normale provare emozioni contrastanti quando si intraprende la fase successiva di una relazione. Che tu sia eccitato, ansioso o una via di mezzo, Prepare and Enrich ti aiuter\u00e0 a potenziare e rafforzare la tua partnership nel futuro. <\/p>\n        <\/div>\n          <\/div>\n\n    <div class=\"comp-blog-card__link\">\n        <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/prepare-enrich-pre-marriage-counselling\/\"     class=\"comp-button comp-button--default\"\n     tabindex=\"0\" role=\"button\"       >\n    Esplorare  <\/a>\n    <\/div>\n  <\/div>\n        <\/div>\n        <\/div><div class=\"alm-btn-wrap\" style=\"visibility: hidden\" data-rel=\"ajax-load-more\"><button class=\"alm-load-more-btn\" type=\"button\">Carica di pi\u00f9<\/button><\/div><div class=\"alm-no-results\" style=\"display: none;\">Sembra che tu non abbia trovato quello che stai cercando. Prova a utilizzare la funzione di ricerca o a selezionare diverse opzioni di filtro.<\/div><\/div>\n                  <\/div>\n      <\/div>\n\n                <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>I ricercatori hanno scoperto che ogni coppia che sta insieme da molto tempo attraversa fasi distinte, ciascuna con le sue ricompense e sfide. <\/p>","protected":false},"author":7,"featured_media":16811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-16809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","relationship-couples","focus-communication","focus-conflict","focus-divorce-separation"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/posts\/16809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/comments?post=16809"}],"version-history":[{"count":0,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/posts\/16809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/media\/16811"}],"wp:attachment":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/media?parent=16809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/categories?post=16809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/tags?post=16809"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}