{"id":8693,"date":"2022-11-30T14:44:49","date_gmt":"2022-11-30T03:44:49","guid":{"rendered":"https:\/\/www.relationshipsnsw.org.au\/?p=8693"},"modified":"2025-04-24T14:27:11","modified_gmt":"2025-04-24T04:27:11","slug":"how-divorce-affects-teenagers","status":"publish","type":"post","link":"https:\/\/www.relationshipsnsw.org.au\/it\/blog\/how-divorce-affects-teenagers\/","title":{"rendered":"Sostenere i giovani adulti e gli adolescenti attraverso la separazione e il divorzio"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"8693\" class=\"elementor elementor-8693\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a0471d6 e-flex e-con-boxed e-con e-parent\" data-id=\"3a0471d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e54bb2 elementor-widget elementor-widget-text-editor\" data-id=\"2e54bb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Vi sono ampie prove del potenziale impatto negativo che la separazione e il divorzio possono avere sulle famiglie. Con il sostegno, alcuni bambini e giovani possono cavarsela relativamente bene dopo la separazione e il divorzio dei genitori. Tuttavia, <a href=\"https:\/\/habs.uq.edu.au\/article\/2018\/09\/how-will-my-divorce-affect-my-kids#:~:text=While%20the%20average%20effect%20of,of%20parents%20in%20intact%20families.\" target=\"_blank\" rel=\"noopener\">la ricerca mostra<\/a> che i bambini provenienti da famiglie separate hanno il doppio delle probabilit\u00e0 di avere gravi problemi di salute mentale.<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1452198c elementor-widget elementor-widget-text-editor\" data-id=\"1452198c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p class=\"wp-block-paragraph\">Quando i genitori si separano, la loro energia e concentrazione limitate possono ricadere sui figli pi\u00f9 piccoli della famiglia, ed \u00e8 comprensibile. Sfortunatamente, questo pu\u00f2 lasciare adolescenti e giovani adulti con un supporto emotivo insufficiente.<\/p>\n<p>Negli ultimi anni \u00e8 emersa una serie di servizi per le famiglie con figli che hanno subito il divorzio e la separazione dei genitori, tra cui consulenze mirate sui minori, gruppi di sostegno per i minori, programmi di gestione dei casi per famiglie ad alto conflitto e servizi di contatto per i minori.<\/p>\n<p>Mentre questi servizi forniscono una risorsa vitale per le famiglie, c&#039;\u00e8 una crescente consapevolezza dei bisogni spesso insoddisfatti degli adolescenti e dei giovani adulti (fascia di et\u00e0 18-25) delle famiglie che si stanno separando. \u00c8 importante ricordare che i bambini in questa fascia di et\u00e0 hanno problemi molto specifici che possono essere esacerbati quando i genitori divorziano.<\/p>\n<p>Quindi, cosa devi ricordare quando aiuti tuo figlio adolescente o adulto a superare una separazione o un divorzio?<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5db50470 e-flex e-con-boxed e-con e-parent\" data-id=\"5db50470\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f91168 elementor-widget elementor-widget-text-editor\" data-id=\"8f91168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\">Guarda sotto l&#039;aspetto duro<\/span><\/h2>\n<p>Sotto quel personaggio &quot;Non mi interessa&quot;, \u00e8 probabile che il tuo adolescente o bambino adulto sia confuso, arrabbiato e sopraffatto dal tumulto emotivo che deriva dal divorzio dei genitori. I giovani sono spesso riluttanti a mostrare al mondo esterno le loro emozioni, ma \u00e8 probabile che ci sia dolore e delusione sotto quell&#039;aspetto burbero.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254a449e elementor-widget elementor-widget-text-editor\" data-id=\"254a449e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"TextRun SCXW235519497 BCX0\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235519497 BCX0\">Un momento cruciale per lo sviluppo<\/span><\/span><\/h2>\n<p><span class=\"LineBreakBlob BlobObject DragDrop SCXW235519497 BCX0\">L&#039;adolescenza \u00e8 generalmente un momento per trovare l&#039;indipendenza, lasciare il segno nel mondo e scoprire chi sei veramente. Sfortunatamente, la separazione e il divorzio possono facilmente indebolire o sospendere alcuni di questi processi. Anche le sfide della vita adulta stanno appena iniziando a presentarsi, che possono essere ulteriormente aggravate da una separazione e un divorzio. Promuovere la loro istruzione, ottenere un mestiere o iniziare a lavorare, espandere la loro cerchia sociale e sperimentare droghe e alcol fanno tutti parte di queste sfide.\u00a0<\/span><\/p>\n<p><span class=\"LineBreakBlob BlobObject DragDrop SCXW235519497 BCX0\">Il difficile equilibrio come genitore di rimanere in contatto ed essere interessati alle loro vite e comunicare che ci tieni a loro e alla loro sicurezza, dando loro spazio per sviluppare questa indipendenza, dovr\u00e0 essere discusso e negoziato apertamente.<\/span><\/p>\n<p>Forse uno degli aspetti pi\u00f9 difficili del divorzio in questa fase della vita di un giovane \u00e8 che gli adolescenti ei giovani adulti spesso perseguono o sviluppano loro stessi relazioni intime. La disgregazione familiare pu\u00f2 distorcere il senso delle relazioni sentimentali di una persona: ci\u00f2 che pu\u00f2 e non pu\u00f2 sopportare e come si risolve il conflitto. Il tuo comportamento durante la separazione \u00e8 una fantastica opportunit\u00e0 per modellare la risoluzione dei conflitti, il compromesso e, soprattutto, il rispetto.<\/p>\n<p><strong><!-- \/wp:paragraph --><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3bc4f4 elementor-widget elementor-widget-text-editor\" data-id=\"c3bc4f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"TextRun SCXW94072273 BCX0\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW94072273 BCX0\">I bambini pi\u00f9 grandi possono assumere ruoli genitoriali<\/span><span class=\"NormalTextRun SCXW94072273 BCX0\"> durante un divorzio<\/span><\/span><\/h2>\n<p>Quando i genitori si separano, spesso hanno risorse di energia limitate e possono essere consumati da ci\u00f2 che sta accadendo loro e dalle decisioni che devono prendere, trovando difficile concentrarsi completamente sui bisogni dei propri figli. Il bambino pi\u00f9 grande pu\u00f2 consapevolmente o inconsciamente assumere un ruolo genitoriale nei confronti dei fratelli pi\u00f9 piccoli, che a loro volta si rivolgeranno a loro per avere sostegno e sicurezza.<\/p>\n<p>Questo rende le emozioni dell&#039;adolescente e del giovane adulto ancora pi\u00f9 invisibili e loro ancora pi\u00f9 vulnerabili. Aiutarli a trovare la propria voce e comprendere le proprie emozioni mentre sono cos\u00ec concentrati sulla cura degli altri pu\u00f2 essere la chiave per la loro salute mentale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c6a28 elementor-widget elementor-widget-text-editor\" data-id=\"a6c6a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Come aiutare un figlio adulto o un adolescente ad affrontare il divorzio o la separazione dei genitori\u00a0<\/h2>\n<p>Mentre i genitori che divorziano probabilmente sperimenteranno angoscia e dolore per conto proprio, \u00e8 fondamentale sostenersi dando la priorit\u00e0 ai bambini, indipendentemente dalla loro et\u00e0, durante questo difficile processo.\u00a0<\/p>\n<h3>Spiegare le ragioni del divorzio o della separazione<\/h3>\n<p>Prendersi il tempo di sedersi come famiglia per spiegare perch\u00e9 ci si sta separando aiuter\u00e0 bambini, adolescenti e giovani adulti a elaborare e accettare la situazione pi\u00f9 prontamente. Rendere questa et\u00e0 appropriata ed evitare di incolpare pu\u00f2 essere molto difficile. Eseguire ci\u00f2 che potresti dire da qualcuno di cui ti fidi pu\u00f2 essere utile. L&#039;attenzione deve essere il pi\u00f9 possibile su ci\u00f2 che puoi condividere che non far\u00e0 sentire i tuoi figli costretti a schierarsi, affrontare il conflitto, unirsi a battaglie o dover scegliere tra voi. Questo \u00e8 importante per la loro salute mentale.<\/p>\n<h3>Non appoggiarti a tuo figlio per il supporto<\/h3>\n<p>Sebbene alcuni adolescenti o giovani adulti possano sembrare saggi oltre i loro anni, la responsabilit\u00e0 di essere &#039;consolatore e consigliere&#039; per un genitore \u00e8 un enorme fardello emotivo che pu\u00f2 mettere a rischio la loro salute mentale. Molti tenderanno naturalmente la mano per assumere questo ruolo e avranno bisogno che tu li sostenga e li rassicuri. Evita di appoggiarti a loro per il tuo conforto e supporto. Invece, rivolgiti ad amici, familiari adulti o a un professionista per ricevere supporto.<\/p>\n<h3>La stabilit\u00e0 \u00e8 fondamentale<\/h3>\n<p>Proprio come i bambini pi\u00f9 piccoli, gli adolescenti e i giovani adulti prosperano grazie alla stabilit\u00e0 e alla routine. Cerca di evitare di apportare i grandi cambiamenti tutti in una volta o evita di farli del tutto. Meno le loro vite vengono sconvolte, meglio \u00e8. Lo ha dimostrato una ricerca dell&#039;Australian Institute of Family Studies <a href=\"https:\/\/aifs.gov.au\/resources\/policy-and-practice-papers\/parental-separation-adolescent-perspective-what-do-they-say\" target=\"_blank\" rel=\"noopener\">gli adolescenti hanno trovato le interruzioni e le modifiche ai loro programmi di assistenza la parte pi\u00f9 difficile di un divorzio<\/a>. Mentre alcuni degli adolescenti intervistati desideravano ardentemente lo stesso tempo con entrambe le famiglie, altri volevano pi\u00f9 stabilit\u00e0 e meno avanti e indietro tra le famiglie. Potrebbe essere necessario essere flessibili per i genitori, non per adolescenti e giovani adulti.<\/p>\n<h3>Continua a comunicare<\/h3>\n<p>Anche se incontri grugniti e &quot;qualsiasi cosa&quot;, continua a trovare il tempo per parlare con il tuo adolescente o giovane adulto. Il solo fatto di sapere che ci sei per loro e che sei investito nel loro benessere sar\u00e0 un&#039;importante fonte di conforto e rassicurazione. <a href=\"https:\/\/aifs.gov.au\/resources\/policy-and-practice-papers\/parental-separation-adolescent-perspective-what-do-they-say\" target=\"_blank\" rel=\"noopener\">Due adolescenti su tre vogliono dire con quale genitore vivono<\/a> quindi, mentre tu e il tuo ex partner siete i responsabili ultimi delle decisioni, prendetevi del tempo per ascoltare le loro preoccupazioni e opinioni.<\/p>\n<h3>Dai loro uno spazio sicuro per parlare<\/h3>\n<p>Potresti scoprire che il tuo adolescente o giovane adulto sta cercando di salvarti da ulteriori sconvolgimenti assumendo una faccia coraggiosa. Offriti di aiutarli a trovare supporto individuale, poich\u00e9 potrebbero voler parlare, ma non con te. Spesso bambini, adolescenti e giovani adulti si sentono limitati e preoccupati di ferire i sentimenti di uno o entrambi i genitori e\/o di peggiorare le cose. Un consulente o uno psicologo sar\u00e0 in grado di fornire un luogo sicuro in cui tuo figlio possa elaborare onestamente i propri sentimenti.<\/p>\n<h3>Proteggili dal conflitto<\/h3>\n<p>Riduci al minimo i conflitti tra te e l&#039;altro genitore. Cerca di costruire una forte alleanza di co-genitorialit\u00e0 quando possibile e cerca aiuto per farlo se necessario. Quando il conflitto \u00e8 alto, potrebbe essere necessario essere pi\u00f9 simili alla genitorialit\u00e0 parallela in cui ti avvicini alla genitorialit\u00e0 in modo diverso, ma lavori sodo per non indebolirti a vicenda quando i bambini trascorrono del tempo con ciascuno di voi.<\/p>\n<p>Ricorda, anche nella separazione stai ancora modellando come condurre le relazioni interpersonali con i tuoi figli.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33241ee e-flex e-con-boxed e-con e-parent\" data-id=\"33241ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b125a1e elementor-widget elementor-widget-spacer\" data-id=\"b125a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f88dfc7 elementor-widget elementor-widget-text-editor\" data-id=\"f88dfc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\">Se hai bisogno di ulteriori informazioni o supporto, <\/span><span lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"none\">Relazioni Australia NSW<\/span><span lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\"> ha una serie di risorse per aiutarti a sostenere tuo figlio adolescente o adulto durante il divorzio o la separazione. Potrebbero trarne vantaggio <\/span><a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/individual-counselling\/\"><span lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"none\">consulenza individuale<\/span><\/a><span lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\">, o <a href=\"https:\/\/www.relationshipsnsw.org.au\/it\/support\/services\/adolescent-family-therapy\/\">Consulenza familiare per adolescenti<\/a>.<\/span><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Dietro la maschera del &quot;non mi interessa&quot;, \u00e8 probabile che il tuo adolescente o il tuo giovane adulto si senta confuso, arrabbiato e sopraffatto.<\/p>","protected":false},"author":3,"featured_media":11018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-8693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","relationship-couples","relationship-families","focus-divorce-separation","focus-parenting"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/posts\/8693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/comments?post=8693"}],"version-history":[{"count":0,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/posts\/8693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/media\/11018"}],"wp:attachment":[{"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/media?parent=8693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/categories?post=8693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.relationshipsnsw.org.au\/it\/wp-json\/wp\/v2\/tags?post=8693"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}